{"id":1197,"date":"2026-05-06T13:30:13","date_gmt":"2026-05-06T03:30:13","guid":{"rendered":"https:\/\/gcc.clients.ionata.com.au\/?page_id=1197"},"modified":"2026-06-02T12:43:15","modified_gmt":"2026-06-02T02:43:15","slug":"landslide-areas","status":"publish","type":"page","link":"https:\/\/www.gcc.tas.gov.au\/es\/for-residents\/your-home-2\/landslide-areas\/","title":{"rendered":"Landslide Areas"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Is your property affected?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Landslide risk areas are identified in the Tasmanian Planning Scheme \u2014 Glenorchy. You can check whether your property is affected using the Discover Glenorchy mapping tool or by contacting our Planning team.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>What does this mean for your property?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">If your property is in a landslide risk area, any proposed development may require a geotechnical report from a qualified engineer. The report assesses the risk and recommends how to manage it.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Planning requirements<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Development in landslide risk areas must meet specific planning requirements. Talk to our Planning team before starting any development work.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Contact<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Phone: 03 6216 6800 (ask for Planning).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Email: gccmail@gcc.tas.gov.au<\/p>","protected":false},"excerpt":{"rendered":"<p>Is your property affected? Landslide risk areas are identified in the Tasmanian Planning Scheme \u2014 Glenorchy. You can check whether your property is affected using the Discover Glenorchy mapping tool or by contacting our Planning team. What does this mean for your property? If your property is in a landslide risk area, any proposed development&hellip;<\/p>","protected":false},"author":1,"featured_media":1199,"parent":1181,"menu_order":168,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_mo_disable_npp":"","ep_embedding_exclude":false,"ep_embedding_include":false,"ep_exclude_from_search":false,"footnotes":""},"class_list":["post-1197","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Landslide Areas - Glenorchy City Council<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gcc.tas.gov.au\/es\/for-residents\/your-home-2\/landslide-areas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landslide Areas - Glenorchy City Council\" \/>\n<meta property=\"og:description\" content=\"Is your property affected? Landslide risk areas are identified in the Tasmanian Planning Scheme \u2014 Glenorchy. You can check whether your property is affected using the Discover Glenorchy mapping tool or by contacting our Planning team. What does this mean for your property? If your property is in a landslide risk area, any proposed development&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gcc.tas.gov.au\/es\/for-residents\/your-home-2\/landslide-areas\/\" \/>\n<meta property=\"og:site_name\" content=\"Glenorchy City Council\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T02:43:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/\",\"url\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/\",\"name\":\"Landslide Areas - Glenorchy City Council\",\"isPartOf\":{\"@id\":\"https:\/\/www.gcc.tas.gov.au\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp\",\"datePublished\":\"2026-05-06T03:30:13+00:00\",\"dateModified\":\"2026-06-02T02:43:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#primaryimage\",\"url\":\"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp\",\"contentUrl\":\"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.gcc.tas.gov.au\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For Residents\",\"item\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Your Home\",\"item\":\"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Landslide Areas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gcc.tas.gov.au\/#website\",\"url\":\"https:\/\/www.gcc.tas.gov.au\/\",\"name\":\"Glenorchy City Council\",\"description\":\"Tasmania&#039;s most diverse city\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.gcc.tas.gov.au\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landslide Areas - Glenorchy City Council","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gcc.tas.gov.au\/es\/for-residents\/your-home-2\/landslide-areas\/","og_locale":"es_ES","og_type":"article","og_title":"Landslide Areas - Glenorchy City Council","og_description":"Is your property affected? Landslide risk areas are identified in the Tasmanian Planning Scheme \u2014 Glenorchy. You can check whether your property is affected using the Discover Glenorchy mapping tool or by contacting our Planning team. What does this mean for your property? If your property is in a landslide risk area, any proposed development&hellip;","og_url":"https:\/\/www.gcc.tas.gov.au\/es\/for-residents\/your-home-2\/landslide-areas\/","og_site_name":"Glenorchy City Council","article_modified_time":"2026-06-02T02:43:15+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/","url":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/","name":"Landslide Areas - Glenorchy City Council","isPartOf":{"@id":"https:\/\/www.gcc.tas.gov.au\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#primaryimage"},"image":{"@id":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#primaryimage"},"thumbnailUrl":"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp","datePublished":"2026-05-06T03:30:13+00:00","dateModified":"2026-06-02T02:43:15+00:00","breadcrumb":{"@id":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#primaryimage","url":"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp","contentUrl":"https:\/\/gcc.assets.ionatahosting.net\/uploads\/2026\/05\/Landslides.webp","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/landslide-areas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gcc.tas.gov.au\/"},{"@type":"ListItem","position":2,"name":"For Residents","item":"https:\/\/www.gcc.tas.gov.au\/for-residents\/"},{"@type":"ListItem","position":3,"name":"Your Home","item":"https:\/\/www.gcc.tas.gov.au\/for-residents\/your-home-2\/"},{"@type":"ListItem","position":4,"name":"Landslide Areas"}]},{"@type":"WebSite","@id":"https:\/\/www.gcc.tas.gov.au\/#website","url":"https:\/\/www.gcc.tas.gov.au\/","name":"Glenorchy City Council","description":"Tasmania&#039;s most diverse city","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gcc.tas.gov.au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/pages\/1197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/comments?post=1197"}],"version-history":[{"count":3,"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/pages\/1197\/revisions"}],"predecessor-version":[{"id":3894,"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/pages\/1197\/revisions\/3894"}],"up":[{"embeddable":true,"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/pages\/1181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/media\/1199"}],"wp:attachment":[{"href":"https:\/\/www.gcc.tas.gov.au\/es\/wp-json\/wp\/v2\/media?parent=1197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}